{"id":1721,"date":"2022-01-30T20:18:17","date_gmt":"2022-01-30T20:18:17","guid":{"rendered":"https:\/\/mundanopedia.com\/?p=1721"},"modified":"2025-09-28T19:29:28","modified_gmt":"2025-09-28T19:29:28","slug":"conciliacion-bancaria","status":"publish","type":"post","link":"https:\/\/mundanopedia.com\/es\/contabilidad\/contabilidad-lntermedia\/conciliacion-bancaria\/","title":{"rendered":"Conciliaci\u00f3n Bancaria: Qu\u00e9 es, M\u00e9todos, C\u00f3mo Hacerla y Ejemplos"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"1721\" class=\"elementor elementor-1721\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-706243f0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"706243f0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-169893d1\" data-id=\"169893d1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-30c0b5e elementor-widget elementor-widget-heading\" data-id=\"30c0b5e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Conciliaci\u00f3n Bancaria: Qu\u00e9 es, M\u00e9todos, C\u00f3mo Hacerla y Ejemplos<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2b02fac7 elementor-widget elementor-widget-text-editor\" data-id=\"2b02fac7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2><strong>Conciliaci\u00f3n bancaria<\/strong><\/h2><p>La conciliaci\u00f3n bancaria es un proceso con el que se identifican y confrontan las diferencias entre lo que la empresa contabiliz\u00f3 de sus cuentas bancarias y lo que los libros reportan en su estado de cuentas.<\/p><p>Su funci\u00f3n es llevar un control que ayuda a descubrir y corregir errores o diferencias entre las cuentas en los libros y el estado bancario.<\/p><p>Su importancia radica en que es un mecanismo de control interno de las empresas, verifica que se hagan bien las anotaciones de cobros y pagos efectuados en un periodo de tiempo, evita errores y proporciona un estado depurado y fiable<\/p><h3><strong>T\u00e9rminos comunes en la conciliaci\u00f3n bancaria<\/strong><\/h3><ul><li><b>Cheques en tr\u00e1nsito: <\/b>Son los cheques que han sido emitidos, pero c\u00f3mo el beneficiario no los ha ido a cobrar, este no se ha registrado en el banco, por lo que se dice que est\u00e1 en \u201ccirculaci\u00f3n\u201d<\/li><li><b>Dep\u00f3sitos en tr\u00e1nsito: <\/b>Son dep\u00f3sitos que fueron hechos a finales de mes por lo que el banco no los registra, lo que significa que estar\u00e1n registrados en los libros de la empresa pero no en el estado de cuenta del mes<\/li><li><b>Notas de cr\u00e9dito: <\/b>Son documentos que le informan a la empresa que le ha entrado una determinada cantidad de dinero por concepto de pagares, intereses, giros, entre otros, pero que no se han cargado en los libros<\/li><li><b>Notas de d\u00e9bito:<\/b> Son documentos que le informan a la empresa que se le ha sustra\u00eddo una determinada cantidad de dinero por cargos ya sean cobro de intereses, comisiones, entre otros.<\/li><\/ul><h3><strong>M\u00e9todos de conciliaci\u00f3n bancaria<\/strong><\/h3><h4><strong>\u00a0<\/strong><\/h4><h4><strong> \u00a01. Conciliaci\u00f3n bancaria por encuentro de saldos o saldos encontrados<\/strong><\/h4><p>Se hace partiendo del saldo final del estado de cuentas para llegar al saldo final que muestran los libros de la empresa o viceversa. Consiste en ajustar el saldo del estado de cuenta, que presenta el banco, hasta llegar al saldo que muestra la cuenta del banco en el mayor de la empresa, de la siguiente manera:<\/p><ol><li>Se le suman a dicho saldo del banco las siguientes partidas:<\/li><\/ol><ul><li style=\"list-style-type: none;\"><ul><li>Los cargos hechos en los libros de la empresa, que el banco no ha abonado todav\u00eda, tales como: Dep\u00f3sitos de \u00faltima hora, errores u<\/li><li>Los cargos efectuados por el banco y que la empresa a\u00fan no ha abonado, por falta de noticias, tales como: comisiones, intereses, errores u<\/li><\/ul><\/li><\/ul><p>\u00a0 \u00a0 \u00a0 \u00a0 2. Se le restan al subtotal obtenido hasta aqu\u00ed, las partidas siguientes:<\/p><ul><li style=\"list-style-type: none;\"><ul><li style=\"list-style-type: none;\"><ul><li>Los abonos hechos por la empresa y que todav\u00eda el banco no hubiere cargado, tales como: Los cheques emitidos por la empresa y no presentados al cobro todav\u00eda, errores u omisiones.<\/li><li>Los abonos hechos efectuados por el banco y que todav\u00eda no hubieren sido cargados por la empresa, tales como: intereses, cobros hechos por el banco en nombre de la empresa, errores u omisiones.<\/li><\/ul><\/li><\/ul><\/li><\/ul><h4><strong>2. Conciliaci\u00f3n por el m\u00e9todo de las cuatro columnas<\/strong><\/h4><p>Consiste en la elaboraci\u00f3n de una hoja de trabajo de cuatro columnas, dos para el saldo de la empresa y dos para el banco.<\/p><h5><strong>Ejemplo de conciliaci\u00f3n de cuatro (04) columnas<\/strong><\/h5><p>La Empresa Boomerang, C.A. le suministra informaci\u00f3n obtenida del an\u00e1lisis de movimientos del libro mayor y el estado de cuenta bancario del mes de diciembre<br \/>de 2019:<br \/>&#8211; Saldo seg\u00fan Estado de Cuenta Bancario 1.400.820<br \/>&#8211; Saldo seg\u00fan los libros de la Empresa 1.358.820<br \/>&#8211; Cheques emitidos por la Empresa y no presentados al cobro.<br \/>No. 12345 Bs. 50.000<br \/>No. 67890 Bs. 78.000<br \/>No. 55789 Bs. 63.000<br \/>&#8211; Cargos hechos por el Banco y no notificado a la empresa<br \/>&#8211; Comisiones<br \/>Bs. 3.500<br \/>&#8211; Nota de d\u00e9bito por Cheque Devuelto Bs. 20.000<br \/>&#8211; Intereses abonados por el Banco y no registrados por la empresa Bs.2.500<br \/>&#8211; Dep\u00f3sito de fin de mes no registrado por el Banco Bs. 80.000<br \/>&#8211; Cheque de otra empresa cargado por error por el Banco Bs. 30.000<br \/>&#8211; Cheque emitido por la empresa por Bs 20.000 y registrado en libros por Bs 2.000<br \/><strong>Usted debe:<\/strong><br \/>&#8211; Elaborar la conciliaci\u00f3n bancaria correspondiente al mes diciembre de 2019 a trav\u00e9s del m\u00e9todo de las cuatro (4) columnas<\/p><p style=\"text-align: center;\">Boomerang, C.A.<\/p><p style=\"text-align: center;\">Conciliaci\u00f3n bancaria<\/p><p style=\"text-align: center;\">Al 31-12-2019<\/p><table width=\"633\"><tbody><tr><td width=\"234\">\u00a0<\/td><td colspan=\"2\" width=\"196\"><strong>Empresa<\/strong><\/td><td colspan=\"3\" width=\"203\"><strong>Banco<\/strong><\/td><\/tr><tr><td width=\"234\">\u00a0<\/td><td width=\"93\"><strong>Debe<\/strong><\/td><td width=\"103\"><strong>Haber<\/strong><\/td><td width=\"99\"><strong>Debe<\/strong><\/td><td colspan=\"2\" width=\"104\"><strong>Haber<\/strong><\/td><\/tr><tr><td width=\"234\">Saldo al 31-12-2019<\/td><td width=\"93\">1.358.820,00<\/td><td width=\"103\">\u00a0<\/td><td colspan=\"2\" width=\"101\">\u00a0<\/td><td width=\"102\">1.400.820,00<\/td><\/tr><tr><td width=\"234\">Deposito en transito<\/td><td width=\"93\">\u00a0<\/td><td width=\"103\">\u00a0<\/td><td colspan=\"2\" width=\"101\">\u00a0<\/td><td width=\"102\">80.000,00<\/td><\/tr><tr><td width=\"234\">Cheques en transito<\/td><td width=\"93\">\u00a0<\/td><td width=\"103\">\u00a0<\/td><td colspan=\"2\" width=\"101\">191.000,00<\/td><td width=\"102\">\u00a0<\/td><\/tr><tr><td width=\"234\">Cheque No. 12345 Bs. 50.000<\/td><td width=\"93\">\u00a0<\/td><td width=\"103\">\u00a0<\/td><td colspan=\"2\" width=\"101\">\u00a0<\/td><td width=\"102\">\u00a0<\/td><\/tr><tr><td width=\"234\">Cheque No. 67890 Bs. 78.000<\/td><td width=\"93\">\u00a0<\/td><td width=\"103\">\u00a0<\/td><td colspan=\"2\" width=\"101\">\u00a0<\/td><td width=\"102\">\u00a0<\/td><\/tr><tr><td width=\"234\">Cheque No. 55789 Bs. 63.000<\/td><td width=\"93\">\u00a0<\/td><td width=\"103\">\u00a0<\/td><td colspan=\"2\" width=\"101\">\u00a0<\/td><td width=\"102\">\u00a0<\/td><\/tr><tr><td width=\"234\">Notas de d\u00e9bito<\/td><td width=\"93\">\u00a0<\/td><td width=\"103\">23.500,00<\/td><td colspan=\"2\" width=\"101\">\u00a0<\/td><td width=\"102\">\u00a0<\/td><\/tr><tr><td width=\"234\">Comisiones \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a03.500<\/td><td width=\"93\">\u00a0<\/td><td width=\"103\">\u00a0<\/td><td colspan=\"2\" width=\"101\">\u00a0<\/td><td width=\"102\">\u00a0<\/td><\/tr><tr><td width=\"234\">Cheque devuelto \u00a0\u00a020.000<\/td><td width=\"93\">\u00a0<\/td><td width=\"103\">\u00a0<\/td><td colspan=\"2\" width=\"101\">\u00a0<\/td><td width=\"102\">\u00a0<\/td><\/tr><tr><td width=\"234\">Notas de cr\u00e9dito<\/td><td width=\"93\">\u00a0<\/td><td width=\"103\">\u00a0<\/td><td colspan=\"2\" width=\"101\">\u00a0<\/td><td width=\"102\">\u00a0<\/td><\/tr><tr><td width=\"234\">Intereses ganados<\/td><td width=\"93\">2.500,00<\/td><td width=\"103\">\u00a0<\/td><td colspan=\"2\" width=\"101\">\u00a0<\/td><td width=\"102\">\u00a0<\/td><\/tr><tr><td width=\"234\">Error registrado en libros<\/td><td width=\"93\">\u00a0<\/td><td width=\"103\">18.000,00<\/td><td colspan=\"2\" width=\"101\">\u00a0<\/td><td width=\"102\">\u00a0<\/td><\/tr><tr><td width=\"234\">Cheque 20.000<\/td><td width=\"93\">\u00a0<\/td><td width=\"103\">\u00a0<\/td><td colspan=\"2\" width=\"101\">\u00a0<\/td><td width=\"102\">\u00a0<\/td><\/tr><tr><td width=\"234\">Registro 2.000<\/td><td width=\"93\">\u00a0<\/td><td width=\"103\">\u00a0<\/td><td colspan=\"2\" width=\"101\">\u00a0<\/td><td width=\"102\">\u00a0<\/td><\/tr><tr><td width=\"234\">Cheque cargado por error por el banco<\/td><td width=\"93\">\u00a0<\/td><td width=\"103\">\u00a0<\/td><td colspan=\"2\" width=\"101\">\u00a0<\/td><td width=\"102\">30.000,00<\/td><\/tr><tr><td width=\"234\">Saldos correctos al \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a031-12-2019<\/td><td width=\"93\">\u00a0<\/td><td width=\"103\">1.319.820,00<\/td><td colspan=\"2\" width=\"101\">1.319.820,00<\/td><td width=\"102\">\u00a0<\/td><\/tr><tr><td width=\"234\">\u00a0<\/td><td width=\"93\">1.361.320,00<\/td><td width=\"103\">1.361.320,00<\/td><td colspan=\"2\" width=\"101\">1.510.820,00<\/td><td width=\"102\">1.510.820,00<\/td><\/tr><tr><td width=\"200\">\u00a0<\/td><td width=\"108\">\u00a0<\/td><td width=\"108\">\u00a0<\/td><td width=\"107\">\u00a0<\/td><td width=\"2\">\u00a0<\/td><td width=\"108\">\u00a0<\/td><\/tr><\/tbody><\/table><h4><strong>3. Conciliaci\u00f3n por correcci\u00f3n de saldos<\/strong><\/h4><p>Se caracteriza por el tratamiento independiente de los saldos de la empresa y del banco.<\/p><p>Cuando se habla de conciliaci\u00f3n de saldos ajustados se realiza en dos etapas: Una para llevar el saldo del estado de cuenta del banco a la situaci\u00f3n correcta, despu\u00e9s de que en los libros de la empresa, se toma nota de las correcciones a que dan lugar, las operaciones pendientes de registro en el banco.<\/p><p>La otra etapa consiste en llevar el saldo de los libros de la empresa a su justo valor, mediante las anotaciones de las operaciones las cuales la empresa no ten\u00eda conocimiento. En la pr\u00e1ctica se procede as\u00ed: El saldo de la cuenta del banco, en el mayor de la empresa se ha de ajustar por los siguientes conceptos:<\/p><ul><li>Se le suman todos los abonos que el banco hubiere hecho a la empresa y de los cuales, al recibirse el estado de cuenta, es cuando tiene noticias de ellos la empresa, tales como: efectos de la empresa, que el banco ten\u00eda para su cobranza y que los cobr\u00f3 y se los abon\u00f3 en cuenta; abonos por intereses, errores u<\/li><li>Se le restar\u00e1n los cargos que el banco hubiere hecho de la empresa y que aparezcan en el estado de cuenta, tales como: comisiones a favor del banco, cheques depositados en la cuenta bancaria y que el banco los hubiera devuelto, por falta de fondos o cualquier otra<\/li><\/ul><p>Del mismo modo, el saldo que muestra el estado de cuenta enviado por el banco deber\u00e1 hac\u00e9rsele los siguientes ajustes:<\/p><ul><li>Sumarle todos los cargos que le hubiera hecho la empresa, y los cuales no aparezcan en el estado de cuenta, tales como: dep\u00f3sitos de \u00faltima hora, errores u omisiones.<\/li><li>Restarle todos los abonos que la empresa le hizo, y que tampoco aparezcan en el estado de cuenta mensual del banco, tales como: cheques pendiente de cobro, errores u omisiones.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2e09322 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2e09322\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c0de96f\" data-id=\"c0de96f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0f1296a elementor-widget elementor-widget-heading\" data-id=\"0f1296a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ver tambi\u00e9n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b21d1a8 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"b21d1a8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>El Inventario First In First Out o primeras entradas, primeras salidas consiste en relacionar y despachar los art\u00edculos seg\u00fan el orden de llegada.<\/p>","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"elementor_theme","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[152,5],"tags":[193],"class_list":["post-1721","post","type-post","status-publish","format-standard","hentry","category-contabilidad","category-contabilidad-lntermedia","tag-activo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Conciliaci\u00f3n Bancaria: Qu\u00e9 es, M\u00e9todos, C\u00f3mo Hacerla y Ejemplos<\/title>\n<meta name=\"description\" content=\"La conciliaci\u00f3n bancaria es un procedimiento de confrontaci\u00f3n de los registros contables de una empresa y de los bancos para un mejor control del efectivo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mundanopedia.com\/es\/contabilidad\/contabilidad-lntermedia\/conciliacion-bancaria\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Conciliaci\u00f3n Bancaria: Qu\u00e9 es, M\u00e9todos, C\u00f3mo Hacerla y Ejemplos\" \/>\n<meta property=\"og:description\" content=\"La conciliaci\u00f3n bancaria es un procedimiento de confrontaci\u00f3n de los registros contables de una empresa y de los bancos para un mejor control del efectivo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mundanopedia.com\/es\/contabilidad\/contabilidad-lntermedia\/conciliacion-bancaria\/\" \/>\n<meta property=\"og:site_name\" content=\"Mundanopedia\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-30T20:18:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-28T19:29:28+00:00\" \/>\n<meta name=\"author\" content=\"VeronicaGomez01\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"VeronicaGomez01\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/mundanopedia.com\\\/es\\\/contabilidad\\\/contabilidad-lntermedia\\\/conciliacion-bancaria\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mundanopedia.com\\\/contabilidad\\\/contabilidad-lntermedia\\\/conciliacion-bancaria\\\/\"},\"author\":{\"name\":\"VeronicaGomez01\",\"@id\":\"https:\\\/\\\/mundanopedia.com\\\/#\\\/schema\\\/person\\\/93340b921ebfa1daa4a4888660e2f6c6\"},\"headline\":\"Conciliaci\u00f3n Bancaria: Qu\u00e9 es, M\u00e9todos, C\u00f3mo Hacerla y Ejemplos\",\"datePublished\":\"2022-01-30T20:18:17+00:00\",\"dateModified\":\"2025-09-28T19:29:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/mundanopedia.com\\\/contabilidad\\\/contabilidad-lntermedia\\\/conciliacion-bancaria\\\/\"},\"wordCount\":1107,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/mundanopedia.com\\\/#organization\"},\"keywords\":[\"Activo\"],\"articleSection\":[\"Contabilidad\",\"Contabilidad Intermedia\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/mundanopedia.com\\\/es\\\/contabilidad\\\/contabilidad-lntermedia\\\/conciliacion-bancaria\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mundanopedia.com\\\/contabilidad\\\/contabilidad-lntermedia\\\/conciliacion-bancaria\\\/\",\"url\":\"https:\\\/\\\/mundanopedia.com\\\/es\\\/contabilidad\\\/contabilidad-lntermedia\\\/conciliacion-bancaria\\\/\",\"name\":\"Conciliaci\u00f3n Bancaria: Qu\u00e9 es, M\u00e9todos, C\u00f3mo Hacerla y Ejemplos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mundanopedia.com\\\/#website\"},\"datePublished\":\"2022-01-30T20:18:17+00:00\",\"dateModified\":\"2025-09-28T19:29:28+00:00\",\"description\":\"La conciliaci\u00f3n bancaria es un procedimiento de confrontaci\u00f3n de los registros contables de una empresa y de los bancos para un mejor control del efectivo.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mundanopedia.com\\\/es\\\/contabilidad\\\/contabilidad-lntermedia\\\/conciliacion-bancaria\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mundanopedia.com\\\/es\\\/contabilidad\\\/contabilidad-lntermedia\\\/conciliacion-bancaria\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mundanopedia.com\\\/es\\\/contabilidad\\\/contabilidad-lntermedia\\\/conciliacion-bancaria\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mundanopedia.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Conciliaci\u00f3n Bancaria: Qu\u00e9 es, M\u00e9todos, C\u00f3mo Hacerla y Ejemplos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mundanopedia.com\\\/#website\",\"url\":\"https:\\\/\\\/mundanopedia.com\\\/\",\"name\":\"Mundanopedia\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/mundanopedia.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mundanopedia.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mundanopedia.com\\\/#organization\",\"name\":\"Mundanopedia\",\"url\":\"https:\\\/\\\/mundanopedia.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/mundanopedia.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mundanopedia.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/cropped-cropped-Mundanopedia-site-logo.png\",\"contentUrl\":\"https:\\\/\\\/mundanopedia.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/cropped-cropped-Mundanopedia-site-logo.png\",\"width\":610,\"height\":145,\"caption\":\"Mundanopedia\"},\"image\":{\"@id\":\"https:\\\/\\\/mundanopedia.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mundanopedia.com\\\/#\\\/schema\\\/person\\\/93340b921ebfa1daa4a4888660e2f6c6\",\"name\":\"VeronicaGomez01\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e2f629c919304dd84edff3b12cf74860a10dd4db780efd86342343d9f52084a9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e2f629c919304dd84edff3b12cf74860a10dd4db780efd86342343d9f52084a9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e2f629c919304dd84edff3b12cf74860a10dd4db780efd86342343d9f52084a9?s=96&d=mm&r=g\",\"caption\":\"VeronicaGomez01\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Conciliaci\u00f3n Bancaria: Qu\u00e9 es, M\u00e9todos, C\u00f3mo Hacerla y Ejemplos","description":"La conciliaci\u00f3n bancaria es un procedimiento de confrontaci\u00f3n de los registros contables de una empresa y de los bancos para un mejor control del efectivo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mundanopedia.com\/es\/contabilidad\/contabilidad-lntermedia\/conciliacion-bancaria\/","og_locale":"es_ES","og_type":"article","og_title":"Conciliaci\u00f3n Bancaria: Qu\u00e9 es, M\u00e9todos, C\u00f3mo Hacerla y Ejemplos","og_description":"La conciliaci\u00f3n bancaria es un procedimiento de confrontaci\u00f3n de los registros contables de una empresa y de los bancos para un mejor control del efectivo.","og_url":"https:\/\/mundanopedia.com\/es\/contabilidad\/contabilidad-lntermedia\/conciliacion-bancaria\/","og_site_name":"Mundanopedia","article_published_time":"2022-01-30T20:18:17+00:00","article_modified_time":"2025-09-28T19:29:28+00:00","author":"VeronicaGomez01","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"VeronicaGomez01","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mundanopedia.com\/es\/contabilidad\/contabilidad-lntermedia\/conciliacion-bancaria\/#article","isPartOf":{"@id":"https:\/\/mundanopedia.com\/contabilidad\/contabilidad-lntermedia\/conciliacion-bancaria\/"},"author":{"name":"VeronicaGomez01","@id":"https:\/\/mundanopedia.com\/#\/schema\/person\/93340b921ebfa1daa4a4888660e2f6c6"},"headline":"Conciliaci\u00f3n Bancaria: Qu\u00e9 es, M\u00e9todos, C\u00f3mo Hacerla y Ejemplos","datePublished":"2022-01-30T20:18:17+00:00","dateModified":"2025-09-28T19:29:28+00:00","mainEntityOfPage":{"@id":"https:\/\/mundanopedia.com\/contabilidad\/contabilidad-lntermedia\/conciliacion-bancaria\/"},"wordCount":1107,"commentCount":0,"publisher":{"@id":"https:\/\/mundanopedia.com\/#organization"},"keywords":["Activo"],"articleSection":["Contabilidad","Contabilidad Intermedia"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/mundanopedia.com\/es\/contabilidad\/contabilidad-lntermedia\/conciliacion-bancaria\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/mundanopedia.com\/contabilidad\/contabilidad-lntermedia\/conciliacion-bancaria\/","url":"https:\/\/mundanopedia.com\/es\/contabilidad\/contabilidad-lntermedia\/conciliacion-bancaria\/","name":"Conciliaci\u00f3n Bancaria: Qu\u00e9 es, M\u00e9todos, C\u00f3mo Hacerla y Ejemplos","isPartOf":{"@id":"https:\/\/mundanopedia.com\/#website"},"datePublished":"2022-01-30T20:18:17+00:00","dateModified":"2025-09-28T19:29:28+00:00","description":"La conciliaci\u00f3n bancaria es un procedimiento de confrontaci\u00f3n de los registros contables de una empresa y de los bancos para un mejor control del efectivo.","breadcrumb":{"@id":"https:\/\/mundanopedia.com\/es\/contabilidad\/contabilidad-lntermedia\/conciliacion-bancaria\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mundanopedia.com\/es\/contabilidad\/contabilidad-lntermedia\/conciliacion-bancaria\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/mundanopedia.com\/es\/contabilidad\/contabilidad-lntermedia\/conciliacion-bancaria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mundanopedia.com\/"},{"@type":"ListItem","position":2,"name":"Conciliaci\u00f3n Bancaria: Qu\u00e9 es, M\u00e9todos, C\u00f3mo Hacerla y Ejemplos"}]},{"@type":"WebSite","@id":"https:\/\/mundanopedia.com\/#website","url":"https:\/\/mundanopedia.com\/","name":"Mundanopedia","description":"","publisher":{"@id":"https:\/\/mundanopedia.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mundanopedia.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/mundanopedia.com\/#organization","name":"Mundanopedia","url":"https:\/\/mundanopedia.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/mundanopedia.com\/#\/schema\/logo\/image\/","url":"https:\/\/mundanopedia.com\/wp-content\/uploads\/2022\/02\/cropped-cropped-Mundanopedia-site-logo.png","contentUrl":"https:\/\/mundanopedia.com\/wp-content\/uploads\/2022\/02\/cropped-cropped-Mundanopedia-site-logo.png","width":610,"height":145,"caption":"Mundanopedia"},"image":{"@id":"https:\/\/mundanopedia.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/mundanopedia.com\/#\/schema\/person\/93340b921ebfa1daa4a4888660e2f6c6","name":"VeronicaGomez01","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/e2f629c919304dd84edff3b12cf74860a10dd4db780efd86342343d9f52084a9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e2f629c919304dd84edff3b12cf74860a10dd4db780efd86342343d9f52084a9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e2f629c919304dd84edff3b12cf74860a10dd4db780efd86342343d9f52084a9?s=96&d=mm&r=g","caption":"VeronicaGomez01"}}]}},"_links":{"self":[{"href":"https:\/\/mundanopedia.com\/es\/wp-json\/wp\/v2\/posts\/1721","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mundanopedia.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mundanopedia.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mundanopedia.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/mundanopedia.com\/es\/wp-json\/wp\/v2\/comments?post=1721"}],"version-history":[{"count":5,"href":"https:\/\/mundanopedia.com\/es\/wp-json\/wp\/v2\/posts\/1721\/revisions"}],"predecessor-version":[{"id":6909,"href":"https:\/\/mundanopedia.com\/es\/wp-json\/wp\/v2\/posts\/1721\/revisions\/6909"}],"wp:attachment":[{"href":"https:\/\/mundanopedia.com\/es\/wp-json\/wp\/v2\/media?parent=1721"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mundanopedia.com\/es\/wp-json\/wp\/v2\/categories?post=1721"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mundanopedia.com\/es\/wp-json\/wp\/v2\/tags?post=1721"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}